{"id":28347,"date":"2021-12-08T21:40:54","date_gmt":"2021-12-08T18:40:54","guid":{"rendered":"https:\/\/olicatessen.gr\/?post_type=product&#038;p=28347"},"modified":"2022-02-09T00:21:39","modified_gmt":"2022-02-08T21:21:39","slug":"dikotylon-fine-lentils","status":"publish","type":"product","link":"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/","title":{"rendered":"Dikotylon &#8211; Fine Lentils"},"content":{"rendered":"<p><strong>Dikotylon &#8211; Fine Lentils!<\/strong><\/p>\n<p><strong>Lentils<\/strong> have the third highest level of <strong>protein<\/strong> and are considered one of the five healthiest foods. They are also a good source of <strong>iron<\/strong> and contain more than half a person&#8217;s daily allowable iron in a cup serving.<\/p>\n<p>500g<\/p>\n<p>More legumes <a href=\"https:\/\/olicatessen.gr\/en\/product-category\/pasta-legumes\/legumes\/?avia_extended_shop_select=yes&amp;product_order=date\">here<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dikotylon &#8211; Fine Lentils! Lentils have the third highest level of protein and are considered one of the five healthiest foods. They are also a good source of iron and contain more than half a person&#8217;s daily allowable iron in a cup serving. 500g More legumes here.<\/p>\n","protected":false},"featured_media":28351,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[431],"product_tag":[],"class_list":{"0":"post-28347","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-legumes","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dikotylon - Fine Lentils - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7<\/title>\n<meta name=\"description\" content=\"Dikotylon - Fine Lentils\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dikotylon - Fine Lentils - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"og:description\" content=\"Dikotylon - Fine Lentils\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/\" \/>\n<meta property=\"og:site_name\" content=\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/olicatessenskg\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-08T21:21:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olicatessen.gr\/wp-content\/uploads\/2021\/12\/dikotylon-small-brown-lentil.jpeg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/dikotylon-fine-lentils\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/dikotylon-fine-lentils\\\/\",\"name\":\"Dikotylon - Fine Lentils - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/dikotylon-fine-lentils\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/dikotylon-fine-lentils\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dikotylon-small-brown-lentil.jpeg.jpg\",\"datePublished\":\"2021-12-08T18:40:54+00:00\",\"dateModified\":\"2022-02-08T21:21:39+00:00\",\"description\":\"Dikotylon - Fine Lentils\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/dikotylon-fine-lentils\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/dikotylon-fine-lentils\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/dikotylon-fine-lentils\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dikotylon-small-brown-lentil.jpeg.jpg\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dikotylon-small-brown-lentil.jpeg.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"\u0394\u03b9\u03ba\u03cc\u03c4\u03c5\u03bb\u03bf\u03bd - \u03a6\u03b1\u03ba\u03ad\u03c2 \u03a8\u03b9\u03bb\u03ad\u03c2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/dikotylon-fine-lentils\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dikotylon &#8211; Fine Lentils\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"name\":\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"description\":\"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio\",\"publisher\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olicatessen.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\",\"name\":\"Olicatessen modern Greek food store\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"width\":1181,\"height\":250,\"caption\":\"Olicatessen modern Greek food store\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/olicatessenskg\",\"https:\\\/\\\/www.instagram.com\\\/olicatessen_skg\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dikotylon - Fine Lentils - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Dikotylon - Fine Lentils","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/","og_locale":"en_US","og_type":"article","og_title":"Dikotylon - Fine Lentils - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","og_description":"Dikotylon - Fine Lentils","og_url":"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/","og_site_name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","article_publisher":"https:\/\/www.facebook.com\/olicatessenskg","article_modified_time":"2022-02-08T21:21:39+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2021\/12\/dikotylon-small-brown-lentil.jpeg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/","url":"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/","name":"Dikotylon - Fine Lentils - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","isPartOf":{"@id":"https:\/\/olicatessen.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/#primaryimage"},"image":{"@id":"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/#primaryimage"},"thumbnailUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2021\/12\/dikotylon-small-brown-lentil.jpeg.jpg","datePublished":"2021-12-08T18:40:54+00:00","dateModified":"2022-02-08T21:21:39+00:00","description":"Dikotylon - Fine Lentils","breadcrumb":{"@id":"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/#primaryimage","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2021\/12\/dikotylon-small-brown-lentil.jpeg.jpg","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2021\/12\/dikotylon-small-brown-lentil.jpeg.jpg","width":1200,"height":1200,"caption":"\u0394\u03b9\u03ba\u03cc\u03c4\u03c5\u03bb\u03bf\u03bd - \u03a6\u03b1\u03ba\u03ad\u03c2 \u03a8\u03b9\u03bb\u03ad\u03c2"},{"@type":"BreadcrumbList","@id":"https:\/\/olicatessen.gr\/en\/product\/dikotylon-fine-lentils\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/olicatessen.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/olicatessen.gr\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Dikotylon &#8211; Fine Lentils"}]},{"@type":"WebSite","@id":"https:\/\/olicatessen.gr\/#website","url":"https:\/\/olicatessen.gr\/","name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio","publisher":{"@id":"https:\/\/olicatessen.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olicatessen.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/olicatessen.gr\/#organization","name":"Olicatessen modern Greek food store","url":"https:\/\/olicatessen.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","width":1181,"height":250,"caption":"Olicatessen modern Greek food store"},"image":{"@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/olicatessenskg","https:\/\/www.instagram.com\/olicatessen_skg\/"]}]}},"_links":{"self":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product\/28347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/comments?post=28347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media\/28351"}],"wp:attachment":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media?parent=28347"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_brand?post=28347"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_cat?post=28347"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_tag?post=28347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}