{"id":31814,"date":"2022-03-01T19:31:42","date_gmt":"2022-03-01T16:31:42","guid":{"rendered":"https:\/\/olicatessen.gr\/?post_type=product&#038;p=31814"},"modified":"2022-04-04T20:25:54","modified_gmt":"2022-04-04T17:25:54","slug":"nomad-organic-honey-from-wildflowers-and-herbs-of-vikos-gorge-500g","status":"publish","type":"product","link":"https:\/\/olicatessen.gr\/en\/product\/nomad-organic-honey-from-wildflowers-and-herbs-of-vikos-gorge-500g\/","title":{"rendered":"Nomad &#8211; Organic Honey from Wildflowers and Herbs of Vikos Gorge, 500g"},"content":{"rendered":"<p><strong>Nomad &#8211; Organic Honey from Wildflowers and Herbs of Vikos Gorge!<\/strong><\/p>\n<p>From the Vikos Gorge, one of the most inaccessible parts of the famous gorge, Nomad bees collect the souls of mountain herbs and wildflowers.<\/p>\n<p>This year the wild mint has given its freshness to the aftertaste of this exceptional and very rare mountain honey. A unique organic flower-herb honey of very limited production from the area of the Vikos Gorge (NATURA 2000).<\/p>\n<p>500g<\/p>\n<p>More honey <a href=\"https:\/\/olicatessen.gr\/en\/product-category\/honey\/\">here<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>More honey <a href=\"https:\/\/olicatessen.gr\/en\/product-category\/honey\/\">here<\/a>.<\/p>\n","protected":false},"featured_media":22941,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[409],"product_tag":[],"class_list":{"0":"post-31814","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-honey","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge, 500g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7<\/title>\n<meta name=\"description\" content=\"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge, 500g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"og:description\" content=\"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/\" \/>\n<meta property=\"og:site_name\" content=\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/olicatessenskg\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-04T17:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olicatessen.gr\/wp-content\/uploads\/2021\/09\/nomad-honey-wildflowers-herbs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1041\" \/>\n\t<meta property=\"og:image:height\" content=\"1040\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\\\/\",\"name\":\"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge, 500g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/nomad-honey-wildflowers-herbs.jpg\",\"datePublished\":\"2022-03-01T16:31:42+00:00\",\"dateModified\":\"2022-04-04T17:25:54+00:00\",\"description\":\"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olicatessen.gr\\\/product\\\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/nomad-honey-wildflowers-herbs.jpg\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/nomad-honey-wildflowers-herbs.jpg\",\"width\":1041,\"height\":1040,\"caption\":\"Nomad - \u0392\u03b9\u03bf\u03bb\u03bf\u03b3\u03b9\u03ba\u03cc \u039c\u03ad\u03bb\u03b9 \u03b1\u03c0\u03cc \u0391\u03b3\u03c1\u03b9\u03bf\u03bb\u03bf\u03cd\u03bb\u03bf\u03c5\u03b4\u03b1 & \u0392\u03cc\u03c4\u03b1\u03bd\u03b1 \u03a7\u03b1\u03c1\u03ac\u03b4\u03c1\u03b1\u03c2 \u0392\u03af\u03ba\u03bf\u03c5\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nomad &#8211; Organic Honey from Wildflowers and Herbs of Vikos Gorge, 500g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"name\":\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"description\":\"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio\",\"publisher\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olicatessen.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\",\"name\":\"Olicatessen modern Greek food store\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"width\":1181,\"height\":250,\"caption\":\"Olicatessen modern Greek food store\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/olicatessenskg\",\"https:\\\/\\\/www.instagram.com\\\/olicatessen_skg\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge, 500g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/","og_locale":"en_US","og_type":"article","og_title":"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge, 500g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","og_description":"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge","og_url":"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/","og_site_name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","article_publisher":"https:\/\/www.facebook.com\/olicatessenskg","article_modified_time":"2022-04-04T17:25:54+00:00","og_image":[{"width":1041,"height":1040,"url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2021\/09\/nomad-honey-wildflowers-herbs.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/","url":"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/","name":"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge, 500g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","isPartOf":{"@id":"https:\/\/olicatessen.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/#primaryimage"},"image":{"@id":"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/#primaryimage"},"thumbnailUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2021\/09\/nomad-honey-wildflowers-herbs.jpg","datePublished":"2022-03-01T16:31:42+00:00","dateModified":"2022-04-04T17:25:54+00:00","description":"Nomad - Organic Honey from Wildflowers and Herbs of Vikos Gorge","breadcrumb":{"@id":"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/#primaryimage","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2021\/09\/nomad-honey-wildflowers-herbs.jpg","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2021\/09\/nomad-honey-wildflowers-herbs.jpg","width":1041,"height":1040,"caption":"Nomad - \u0392\u03b9\u03bf\u03bb\u03bf\u03b3\u03b9\u03ba\u03cc \u039c\u03ad\u03bb\u03b9 \u03b1\u03c0\u03cc \u0391\u03b3\u03c1\u03b9\u03bf\u03bb\u03bf\u03cd\u03bb\u03bf\u03c5\u03b4\u03b1 & \u0392\u03cc\u03c4\u03b1\u03bd\u03b1 \u03a7\u03b1\u03c1\u03ac\u03b4\u03c1\u03b1\u03c2 \u0392\u03af\u03ba\u03bf\u03c5"},{"@type":"BreadcrumbList","@id":"https:\/\/olicatessen.gr\/product\/nomad-biologiko-meli-apo-agrioloulouda-botana-xaradras-vikou-500g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/olicatessen.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/olicatessen.gr\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Nomad &#8211; Organic Honey from Wildflowers and Herbs of Vikos Gorge, 500g"}]},{"@type":"WebSite","@id":"https:\/\/olicatessen.gr\/#website","url":"https:\/\/olicatessen.gr\/","name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio","publisher":{"@id":"https:\/\/olicatessen.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olicatessen.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/olicatessen.gr\/#organization","name":"Olicatessen modern Greek food store","url":"https:\/\/olicatessen.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","width":1181,"height":250,"caption":"Olicatessen modern Greek food store"},"image":{"@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/olicatessenskg","https:\/\/www.instagram.com\/olicatessen_skg\/"]}]}},"_links":{"self":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product\/31814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/comments?post=31814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media\/22941"}],"wp:attachment":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media?parent=31814"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_brand?post=31814"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_cat?post=31814"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_tag?post=31814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}