{"id":55500,"date":"2024-01-19T23:20:28","date_gmt":"2024-01-19T20:20:28","guid":{"rendered":"https:\/\/olicatessen.gr\/?post_type=product&#038;p=55500"},"modified":"2025-12-16T00:07:56","modified_gmt":"2025-12-15T21:07:56","slug":"sirra-organics-liquid-soap-peppermint-rosemary-500ml","status":"publish","type":"product","link":"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/","title":{"rendered":"Sirra Organics &#8211; Liquid Soap Peppermint &amp; Rosemary, 500ml"},"content":{"rendered":"<p><strong>Sirra Organics &#8211; Liquid Soap Peppermint &amp; Rosemary!<\/strong><\/p>\n<p><strong>Natural liquid soap<\/strong> made in Greece from simple, pure and natural ingredients. It cleanses and moisturizes the skin, creating a unique feeling of freshness and cleanliness. Suitable for <strong>face<\/strong> and body, suits every skin type.<\/p>\n<p>It contains <strong>extra virgin olive oil, <\/strong>coconut oil, jojoba oil, castor oil, glycerin and <strong>essential oils of peppermint<\/strong> and <strong>rosemary.<\/strong><\/p>\n<p>500ml<\/p>\n<p>&nbsp;<\/p>\n<p>Sirra Organics &#8211; Liquid Soap Peppermint &amp; Rosemary and more soaps <a href=\"https:\/\/olicatessen.gr\/en\/product-category\/soaps-en\/\">here<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sirra Organics &#8211; Liquid Soap Peppermint &amp; Rosemary! Natural liquid soap made in Greece from simple, pure and natural ingredients. It cleanses and moisturizes the skin, creating a unique feeling of freshness and cleanliness. Suitable for face and body, suits every skin type. It contains extra virgin olive oil, coconut oil, jojoba oil, castor oil, [&hellip;]<\/p>\n","protected":false},"featured_media":50607,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[689],"product_tag":[],"class_list":{"0":"post-55500","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-soaps-en","8":"first","9":"outofstock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sirra Organics - Liquid Soap Peppermint &amp; Rosemary, 500ml - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7<\/title>\n<meta name=\"description\" content=\"Get Sirra Organics - Liquid Soap Peppermint &amp; Rosemary! Natural liquid soap made in Greece from simple, pure and natural ingredients.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sirra Organics - Liquid Soap Peppermint &amp; Rosemary, 500ml - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"og:description\" content=\"Get Sirra Organics - Liquid Soap Peppermint &amp; Rosemary! Natural liquid soap made in Greece from simple, pure and natural ingredients.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/olicatessenskg\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T21:07:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olicatessen.gr\/wp-content\/uploads\/2023\/09\/sirra-organics-peppermint-rosemary.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1041\" \/>\n\t<meta property=\"og:image:height\" content=\"1041\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\\\/\",\"name\":\"Sirra Organics - Liquid Soap Peppermint &amp; Rosemary, 500ml - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/sirra-organics-peppermint-rosemary.png\",\"datePublished\":\"2024-01-19T20:20:28+00:00\",\"dateModified\":\"2025-12-15T21:07:56+00:00\",\"description\":\"Get Sirra Organics - Liquid Soap Peppermint & Rosemary! Natural liquid soap made in Greece from simple, pure and natural ingredients.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/sirra-organics-peppermint-rosemary.png\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/sirra-organics-peppermint-rosemary.png\",\"width\":1041,\"height\":1041,\"caption\":\"Sirra Organics - Liquid Soap Peppermint &amp; Rosemary\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sirra Organics &#8211; Liquid Soap Peppermint &amp; Rosemary, 500ml\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"name\":\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"description\":\"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio\",\"publisher\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olicatessen.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\",\"name\":\"Olicatessen modern Greek food store\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"width\":1181,\"height\":250,\"caption\":\"Olicatessen modern Greek food store\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/olicatessenskg\",\"https:\\\/\\\/www.instagram.com\\\/olicatessen_skg\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sirra Organics - Liquid Soap Peppermint &amp; Rosemary, 500ml - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Get Sirra Organics - Liquid Soap Peppermint & Rosemary! Natural liquid soap made in Greece from simple, pure and natural ingredients.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/","og_locale":"en_US","og_type":"article","og_title":"Sirra Organics - Liquid Soap Peppermint &amp; Rosemary, 500ml - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","og_description":"Get Sirra Organics - Liquid Soap Peppermint & Rosemary! Natural liquid soap made in Greece from simple, pure and natural ingredients.","og_url":"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/","og_site_name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","article_publisher":"https:\/\/www.facebook.com\/olicatessenskg","article_modified_time":"2025-12-15T21:07:56+00:00","og_image":[{"width":1041,"height":1041,"url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2023\/09\/sirra-organics-peppermint-rosemary.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/","url":"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/","name":"Sirra Organics - Liquid Soap Peppermint &amp; Rosemary, 500ml - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","isPartOf":{"@id":"https:\/\/olicatessen.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/#primaryimage"},"image":{"@id":"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/#primaryimage"},"thumbnailUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2023\/09\/sirra-organics-peppermint-rosemary.png","datePublished":"2024-01-19T20:20:28+00:00","dateModified":"2025-12-15T21:07:56+00:00","description":"Get Sirra Organics - Liquid Soap Peppermint & Rosemary! Natural liquid soap made in Greece from simple, pure and natural ingredients.","breadcrumb":{"@id":"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/#primaryimage","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2023\/09\/sirra-organics-peppermint-rosemary.png","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2023\/09\/sirra-organics-peppermint-rosemary.png","width":1041,"height":1041,"caption":"Sirra Organics - Liquid Soap Peppermint &amp; Rosemary"},{"@type":"BreadcrumbList","@id":"https:\/\/olicatessen.gr\/en\/product\/sirra-organics-liquid-soap-peppermint-rosemary-500ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/olicatessen.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/olicatessen.gr\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Sirra Organics &#8211; Liquid Soap Peppermint &amp; Rosemary, 500ml"}]},{"@type":"WebSite","@id":"https:\/\/olicatessen.gr\/#website","url":"https:\/\/olicatessen.gr\/","name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio","publisher":{"@id":"https:\/\/olicatessen.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olicatessen.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/olicatessen.gr\/#organization","name":"Olicatessen modern Greek food store","url":"https:\/\/olicatessen.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","width":1181,"height":250,"caption":"Olicatessen modern Greek food store"},"image":{"@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/olicatessenskg","https:\/\/www.instagram.com\/olicatessen_skg\/"]}]}},"_links":{"self":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product\/55500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/comments?post=55500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media\/50607"}],"wp:attachment":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media?parent=55500"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_brand?post=55500"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_cat?post=55500"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_tag?post=55500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}