{"id":60565,"date":"2024-07-18T21:39:56","date_gmt":"2024-07-18T18:39:56","guid":{"rendered":"https:\/\/olicatessen.gr\/?post_type=product&#038;p=60565"},"modified":"2024-07-24T08:15:37","modified_gmt":"2024-07-24T05:15:37","slug":"phils-hazelicious-choco-granola-%ce%b1%ce%bd%cf%84%ce%b9%ce%b3%cf%81%ce%b1%cf%86%ce%ae","status":"publish","type":"product","link":"https:\/\/olicatessen.gr\/en\/product\/phils-hazelicious-choco-granola-%ce%b1%ce%bd%cf%84%ce%b9%ce%b3%cf%81%ce%b1%cf%86%ce%ae\/","title":{"rendered":"Phil&#8217;s &#8211; Vanilla Choco Granola"},"content":{"rendered":"<p><strong>Phil&#8217;s &#8211; Vanilla Choco Granola!<\/strong><\/p>\n<p>A <strong>homemade granola<\/strong> with excellent <strong>organic<\/strong> farming <strong>ingredients.<\/strong> Contains oat flakes, maple syrup, extra virgin coconut oil, Madagascar vanilla, <strong>vegan chocolate drops<\/strong> and Messolonghi salt. Goes well with milk or yogurt, over a smoothie, as a snack.<\/p>\n<p>275g<\/p>\n<p>More cereals <a href=\"https:\/\/olicatessen.gr\/en\/product-category\/cereals\/\">here<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Phil&#8217;s &#8211; Vanilla Choco Granola! A homemade granola with excellent organic farming ingredients. Contains oat flakes, maple syrup, extra virgin coconut oil, Madagascar vanilla, vegan chocolate drops and Messolonghi salt. Goes well with milk or yogurt, over a smoothie, as a snack. 275g More cereals here.<\/p>\n","protected":false},"featured_media":60563,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[410],"product_tag":[],"class_list":{"0":"post-60565","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cereals","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Phil&#039;s - Vanilla Choco Granola - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7<\/title>\n<meta name=\"description\" content=\"Phil&#039;s - Vanilla Choco Granola\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Phil&#039;s - Vanilla Choco Granola - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"og:description\" content=\"Phil&#039;s - Vanilla Choco Granola\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/\" \/>\n<meta property=\"og:site_name\" content=\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/olicatessenskg\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T05:15:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olicatessen.gr\/wp-content\/uploads\/2024\/07\/phils-vanilla-choco-granola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1090\" \/>\n\t<meta property=\"og:image:height\" content=\"1190\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/phils-vanilla-choco-granola\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/phils-vanilla-choco-granola\\\/\",\"name\":\"Phil's - Vanilla Choco Granola - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/phils-vanilla-choco-granola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/phils-vanilla-choco-granola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/phils-vanilla-choco-granola.png\",\"datePublished\":\"2024-07-18T18:39:56+00:00\",\"dateModified\":\"2024-07-24T05:15:37+00:00\",\"description\":\"Phil's - Vanilla Choco Granola\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/phils-vanilla-choco-granola\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olicatessen.gr\\\/product\\\/phils-vanilla-choco-granola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/phils-vanilla-choco-granola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/phils-vanilla-choco-granola.png\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/phils-vanilla-choco-granola.png\",\"width\":1090,\"height\":1190,\"caption\":\"Phil's - \u0392\u03b1\u03bd\u03af\u03bb\u03b9\u03b1 \u03a3\u03bf\u03ba\u03bf\u03bb\u03ac\u03c4\u03b1 Granola\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/product\\\/phils-vanilla-choco-granola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Phil&#8217;s &#8211; Vanilla Choco Granola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"name\":\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"description\":\"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio\",\"publisher\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olicatessen.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\",\"name\":\"Olicatessen modern Greek food store\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"width\":1181,\"height\":250,\"caption\":\"Olicatessen modern Greek food store\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/olicatessenskg\",\"https:\\\/\\\/www.instagram.com\\\/olicatessen_skg\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Phil's - Vanilla Choco Granola - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Phil's - Vanilla Choco Granola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/","og_locale":"en_US","og_type":"article","og_title":"Phil's - Vanilla Choco Granola - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","og_description":"Phil's - Vanilla Choco Granola","og_url":"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/","og_site_name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","article_publisher":"https:\/\/www.facebook.com\/olicatessenskg","article_modified_time":"2024-07-24T05:15:37+00:00","og_image":[{"width":1090,"height":1190,"url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2024\/07\/phils-vanilla-choco-granola.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/","url":"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/","name":"Phil's - Vanilla Choco Granola - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","isPartOf":{"@id":"https:\/\/olicatessen.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/#primaryimage"},"image":{"@id":"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/#primaryimage"},"thumbnailUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2024\/07\/phils-vanilla-choco-granola.png","datePublished":"2024-07-18T18:39:56+00:00","dateModified":"2024-07-24T05:15:37+00:00","description":"Phil's - Vanilla Choco Granola","breadcrumb":{"@id":"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/#primaryimage","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2024\/07\/phils-vanilla-choco-granola.png","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2024\/07\/phils-vanilla-choco-granola.png","width":1090,"height":1190,"caption":"Phil's - \u0392\u03b1\u03bd\u03af\u03bb\u03b9\u03b1 \u03a3\u03bf\u03ba\u03bf\u03bb\u03ac\u03c4\u03b1 Granola"},{"@type":"BreadcrumbList","@id":"https:\/\/olicatessen.gr\/product\/phils-vanilla-choco-granola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/olicatessen.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/olicatessen.gr\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Phil&#8217;s &#8211; Vanilla Choco Granola"}]},{"@type":"WebSite","@id":"https:\/\/olicatessen.gr\/#website","url":"https:\/\/olicatessen.gr\/","name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio","publisher":{"@id":"https:\/\/olicatessen.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olicatessen.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/olicatessen.gr\/#organization","name":"Olicatessen modern Greek food store","url":"https:\/\/olicatessen.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","width":1181,"height":250,"caption":"Olicatessen modern Greek food store"},"image":{"@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/olicatessenskg","https:\/\/www.instagram.com\/olicatessen_skg\/"]}]}},"_links":{"self":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product\/60565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/comments?post=60565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media\/60563"}],"wp:attachment":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media?parent=60565"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_brand?post=60565"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_cat?post=60565"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_tag?post=60565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}