{"id":65532,"date":"2024-12-14T23:32:06","date_gmt":"2024-12-14T20:32:06","guid":{"rendered":"https:\/\/olicatessen.gr\/product\/black-garlic-downvillage-black-garlic-paste-200g\/"},"modified":"2024-12-17T00:37:01","modified_gmt":"2024-12-16T21:37:01","slug":"black-garlic-downvillage-black-garlic-paste-200g","status":"publish","type":"product","link":"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/","title":{"rendered":"Black Garlic Downvillage &#8211; Black Garlic Paste, 200g"},"content":{"rendered":"<p><strong>Black Garlic Downvillage &#8211; Black Garlic Paste!<\/strong><\/p>\n<p>Black garlic comes from white garlic and is considered a superfood due to its double antioxidant power compared to white garlic. Antioxidants are essential for the proper functioning of the immune system, prevention, repair of damage to the body and inhibition of aging. It first appeared in Japan, Korea and Thailand and in recent years has been gaining ground in the West.<\/p>\n<p>White garlic caramelizes slowly for 40 days, under controlled temperature and humidity conditions. This is how its special flavor characteristics and antioxidant properties develop. Then the cloves are cleaned by hand and only the most perfect ones are selected.<\/p>\n<p>Black garlic paste with light notes of espresso coffee and a soft honey aftertaste. Goes well with salmon, trout, roast beef or sausages.<\/p>\n<p>200g<\/p>\n<p>More savory delicacies <a href=\"https:\/\/olicatessen.gr\/en\/product-category\/savory-delicacies\/\">here<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Black Garlic Downvillage &#8211; Black Garlic Paste! Black garlic comes from white garlic and is considered a superfood due to its double antioxidant power compared to white garlic. Antioxidants are essential for the proper functioning of the immune system, prevention, repair of damage to the body and inhibition of aging. It first appeared in Japan, [&hellip;]<\/p>\n","protected":false},"featured_media":65305,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[408],"product_tag":[],"class_list":{"0":"post-65532","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-savory-delicacies","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Black Garlic Downvillage - Black Garlic Paste, 200g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7<\/title>\n<meta name=\"description\" content=\"Black Garlic Downvillage - Black Garlic Paste\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Black Garlic Downvillage - Black Garlic Paste, 200g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"og:description\" content=\"Black Garlic Downvillage - Black Garlic Paste\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/\" \/>\n<meta property=\"og:site_name\" content=\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/olicatessenskg\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T21:37:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olicatessen.gr\/wp-content\/uploads\/2024\/12\/black-garlic-downvillage-paste-200g.png\" \/>\n\t<meta property=\"og:image:width\" content=\"430\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/black-garlic-downvillage-black-garlic-paste-200g\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/black-garlic-downvillage-black-garlic-paste-200g\\\/\",\"name\":\"Black Garlic Downvillage - Black Garlic Paste, 200g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/black-garlic-downvillage-black-garlic-paste-200g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/black-garlic-downvillage-black-garlic-paste-200g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/black-garlic-downvillage-paste-200g.png\",\"datePublished\":\"2024-12-14T20:32:06+00:00\",\"dateModified\":\"2024-12-16T21:37:01+00:00\",\"description\":\"Black Garlic Downvillage - Black Garlic Paste\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/black-garlic-downvillage-black-garlic-paste-200g\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/black-garlic-downvillage-black-garlic-paste-200g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/black-garlic-downvillage-black-garlic-paste-200g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/black-garlic-downvillage-paste-200g.png\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/black-garlic-downvillage-paste-200g.png\",\"width\":430,\"height\":410,\"caption\":\"Black Garlic Downvillage - \u03a0\u03ac\u03c3\u03c4\u03b1 \u039c\u03b1\u03cd\u03c1\u03bf\u03c5 \u03a3\u03ba\u03cc\u03c1\u03b4\u03bf\u03c5 \u03bc\u03b5 \u03a3\u03b9\u03c1\u03cc\u03c0\u03b9 \u0391\u03b3\u03b1\u03cd\u03b7\u03c2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/black-garlic-downvillage-black-garlic-paste-200g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Black Garlic Downvillage &#8211; Black Garlic Paste, 200g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"name\":\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"description\":\"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio\",\"publisher\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olicatessen.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\",\"name\":\"Olicatessen modern Greek food store\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"width\":1181,\"height\":250,\"caption\":\"Olicatessen modern Greek food store\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/olicatessenskg\",\"https:\\\/\\\/www.instagram.com\\\/olicatessen_skg\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Black Garlic Downvillage - Black Garlic Paste, 200g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Black Garlic Downvillage - Black Garlic Paste","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/","og_locale":"en_US","og_type":"article","og_title":"Black Garlic Downvillage - Black Garlic Paste, 200g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","og_description":"Black Garlic Downvillage - Black Garlic Paste","og_url":"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/","og_site_name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","article_publisher":"https:\/\/www.facebook.com\/olicatessenskg","article_modified_time":"2024-12-16T21:37:01+00:00","og_image":[{"width":430,"height":410,"url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2024\/12\/black-garlic-downvillage-paste-200g.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/","url":"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/","name":"Black Garlic Downvillage - Black Garlic Paste, 200g - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","isPartOf":{"@id":"https:\/\/olicatessen.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/#primaryimage"},"image":{"@id":"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/#primaryimage"},"thumbnailUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2024\/12\/black-garlic-downvillage-paste-200g.png","datePublished":"2024-12-14T20:32:06+00:00","dateModified":"2024-12-16T21:37:01+00:00","description":"Black Garlic Downvillage - Black Garlic Paste","breadcrumb":{"@id":"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/#primaryimage","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2024\/12\/black-garlic-downvillage-paste-200g.png","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2024\/12\/black-garlic-downvillage-paste-200g.png","width":430,"height":410,"caption":"Black Garlic Downvillage - \u03a0\u03ac\u03c3\u03c4\u03b1 \u039c\u03b1\u03cd\u03c1\u03bf\u03c5 \u03a3\u03ba\u03cc\u03c1\u03b4\u03bf\u03c5 \u03bc\u03b5 \u03a3\u03b9\u03c1\u03cc\u03c0\u03b9 \u0391\u03b3\u03b1\u03cd\u03b7\u03c2"},{"@type":"BreadcrumbList","@id":"https:\/\/olicatessen.gr\/en\/product\/black-garlic-downvillage-black-garlic-paste-200g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/olicatessen.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/olicatessen.gr\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Black Garlic Downvillage &#8211; Black Garlic Paste, 200g"}]},{"@type":"WebSite","@id":"https:\/\/olicatessen.gr\/#website","url":"https:\/\/olicatessen.gr\/","name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio","publisher":{"@id":"https:\/\/olicatessen.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olicatessen.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/olicatessen.gr\/#organization","name":"Olicatessen modern Greek food store","url":"https:\/\/olicatessen.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","width":1181,"height":250,"caption":"Olicatessen modern Greek food store"},"image":{"@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/olicatessenskg","https:\/\/www.instagram.com\/olicatessen_skg\/"]}]}},"_links":{"self":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product\/65532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/comments?post=65532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media\/65305"}],"wp:attachment":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media?parent=65532"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_brand?post=65532"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_cat?post=65532"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_tag?post=65532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}