{"id":87099,"date":"2026-03-14T16:00:03","date_gmt":"2026-03-14T13:00:03","guid":{"rendered":"https:\/\/olicatessen.gr\/product\/perbellini-sbrisolada\/"},"modified":"2026-03-16T21:43:10","modified_gmt":"2026-03-16T18:43:10","slug":"perbellini-sbrisolada","status":"publish","type":"product","link":"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/","title":{"rendered":"Perbellini &#8211; Sbrisolada"},"content":{"rendered":"<p data-start=\"3143\" data-end=\"3258\"><strong>Perbellini &#8211; Sbrisolada!<\/strong><\/p>\n<p data-start=\"4953\" data-end=\"5097\">The <strong data-start=\"4955\" data-end=\"4969\">Sbrisolada<\/strong> by Perbellini originates from the historic city of Mantua in Italy\u2019s Lombardy region.<\/p>\n<p data-start=\"5099\" data-end=\"5284\">Its name derives from the local dialect word \u201c<strong data-start=\"5135\" data-end=\"5146\">brisa<\/strong>,\u201d meaning crumb, referring to the way the cake naturally breaks into pieces when enjoyed. <\/p>\n<p data-start=\"5286\" data-end=\"5419\">With its rich almond flavour and crumbly texture, Sbrisolada is traditionally eaten by hand or paired with<strong data-start=\"5339\" data-end=\"5363\"> sweet wine or grappa,<\/strong> highlighting its rustic Italian character.<\/p>\n<p>350g<\/p>\n<p data-start=\"4206\" data-end=\"4486\"><strong data-start=\"4208\" data-end=\"4234\">Pasticceria<\/strong> Perbellini is a historic name in Italian pastry making, with roots dating back to <strong data-start=\"4299\" data-end=\"4307\">1872<\/strong>. The company was founded by Luigi Perbellini in Isola della Scala, near Verona, and has grown through generations of pastry chefs who have preserved the tradition of artisanal confectionery.<\/p>\n<p data-start=\"4488\" data-end=\"4768\">In <strong data-start=\"4491\" data-end=\"4499\">1891<\/strong>, Giovanni Battista Perbellini created the famous <strong data-start=\"4557\" data-end=\"4575\">Offella<\/strong> d\u2019Oro, a soft almond cake that became a symbol of Veronese pastry tradition. Since then, the Perbellini family has continued to craft exceptional desserts that combine heritage, refined technique and carefully selected ingredients, keeping Italian pastry artistry alive. <\/p>\n<p>Perbellini &#8211; Sbrisolada and more <a href=\"https:\/\/olicatessen.gr\/en\/product-category\/colomba-en\/\">here<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perbellini &#8211; Sbrisolada! The Sbrisolada by Perbellini originates from the historic city of Mantua in Italy\u2019s Lombardy region. Its name derives from the local dialect word \u201cbrisa,\u201d meaning crumb, referring to the way the cake naturally breaks into pieces when enjoyed. With its rich almond flavour and crumbly texture, Sbrisolada is traditionally eaten by hand [&hellip;]<\/p>\n","protected":false},"featured_media":87760,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[425],"product_tag":[],"class_list":{"0":"post-87099","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-traditional-sweets","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perbellini - Sbrisolada - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7<\/title>\n<meta name=\"description\" content=\"Sbrisolada Perbellini\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perbellini - Sbrisolada - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"og:description\" content=\"Sbrisolada Perbellini\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/\" \/>\n<meta property=\"og:site_name\" content=\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/olicatessenskg\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-16T18:43:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olicatessen.gr\/wp-content\/uploads\/2026\/03\/SBRISOLADA-PACK-ART.1803-1030x1030.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"1030\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/perbellini-sbrisolada\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/perbellini-sbrisolada\\\/\",\"name\":\"Perbellini - Sbrisolada - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/perbellini-sbrisolada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/perbellini-sbrisolada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/perbellini-sbrisolada-1024x1024-1.jpg\",\"datePublished\":\"2026-03-14T13:00:03+00:00\",\"dateModified\":\"2026-03-16T18:43:10+00:00\",\"description\":\"Sbrisolada Perbellini\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/perbellini-sbrisolada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/perbellini-sbrisolada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/perbellini-sbrisolada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/perbellini-sbrisolada-1024x1024-1.jpg\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/perbellini-sbrisolada-1024x1024-1.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"perbellini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/product\\\/perbellini-sbrisolada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/olicatessen.gr\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Perbellini &#8211; Sbrisolada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#website\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"name\":\"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7\",\"description\":\"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio\",\"publisher\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olicatessen.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#organization\",\"name\":\"Olicatessen modern Greek food store\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"contentUrl\":\"https:\\\/\\\/olicatessen.gr\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo_og.png\",\"width\":1181,\"height\":250,\"caption\":\"Olicatessen modern Greek food store\"},\"image\":{\"@id\":\"https:\\\/\\\/olicatessen.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/olicatessenskg\",\"https:\\\/\\\/www.instagram.com\\\/olicatessen_skg\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perbellini - Sbrisolada - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Sbrisolada Perbellini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/","og_locale":"en_US","og_type":"article","og_title":"Perbellini - Sbrisolada - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","og_description":"Sbrisolada Perbellini","og_url":"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/","og_site_name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","article_publisher":"https:\/\/www.facebook.com\/olicatessenskg","article_modified_time":"2026-03-16T18:43:10+00:00","og_image":[{"width":1030,"height":1030,"url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2026\/03\/SBRISOLADA-PACK-ART.1803-1030x1030.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/","url":"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/","name":"Perbellini - Sbrisolada - Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","isPartOf":{"@id":"https:\/\/olicatessen.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/#primaryimage"},"image":{"@id":"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/#primaryimage"},"thumbnailUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2026\/03\/perbellini-sbrisolada-1024x1024-1.jpg","datePublished":"2026-03-14T13:00:03+00:00","dateModified":"2026-03-16T18:43:10+00:00","description":"Sbrisolada Perbellini","breadcrumb":{"@id":"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/#primaryimage","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2026\/03\/perbellini-sbrisolada-1024x1024-1.jpg","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2026\/03\/perbellini-sbrisolada-1024x1024-1.jpg","width":1024,"height":1024,"caption":"perbellini"},{"@type":"BreadcrumbList","@id":"https:\/\/olicatessen.gr\/en\/product\/perbellini-sbrisolada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/olicatessen.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/olicatessen.gr\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Perbellini &#8211; Sbrisolada"}]},{"@type":"WebSite","@id":"https:\/\/olicatessen.gr\/#website","url":"https:\/\/olicatessen.gr\/","name":"Olicatessen \u0398\u03b5\u03c3\u03c3\u03b1\u03bb\u03bf\u03bd\u03af\u03ba\u03b7","description":"Deli \u25cf Cosmetics \u25cf Kitchen \u25cf Bio","publisher":{"@id":"https:\/\/olicatessen.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olicatessen.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/olicatessen.gr\/#organization","name":"Olicatessen modern Greek food store","url":"https:\/\/olicatessen.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/","url":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","contentUrl":"https:\/\/olicatessen.gr\/wp-content\/uploads\/2017\/06\/logo_og.png","width":1181,"height":250,"caption":"Olicatessen modern Greek food store"},"image":{"@id":"https:\/\/olicatessen.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/olicatessenskg","https:\/\/www.instagram.com\/olicatessen_skg\/"]}]}},"_links":{"self":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product\/87099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/comments?post=87099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media\/87760"}],"wp:attachment":[{"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/media?parent=87099"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_brand?post=87099"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_cat?post=87099"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olicatessen.gr\/en\/wp-json\/wp\/v2\/product_tag?post=87099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}